{"id":3341,"date":"2022-12-14T11:55:05","date_gmt":"2022-12-14T10:55:05","guid":{"rendered":"https:\/\/www.feuer-fuchs.de\/blog\/?p=3341"},"modified":"2025-04-03T14:33:07","modified_gmt":"2025-04-03T12:33:07","slug":"kondenswasser-im-schornstein-und-jetzt-das-koennen-sie-tun","status":"publish","type":"post","link":"https:\/\/www.feuer-fuchs.de\/blog\/kaminofen\/kondenswasser-im-schornstein-und-jetzt-das-koennen-sie-tun","title":{"rendered":"Kondenswasser im Schornstein \u2013 und jetzt? Das k\u00f6nnen Sie tun!"},"content":{"rendered":"\n<p>Ein guter <strong>Kondensatablauf<\/strong> f\u00fcr Ihren <strong>Schornstein<\/strong> verl\u00e4ngert das Leben Ihres <a href=\"https:\/\/www.feuer-fuchs.de\/Kamine\">Kamins<\/a> und ist kein gro\u00dfer Aufwand, sowohl in der Montage als auch in der Wartung. Viele Kaminsysteme haben bereits ein <strong>integriertes Entw\u00e4sserungssystem<\/strong>, das unkompliziert an den Abwasseranschluss Ihres Hauses gekoppelt werden kann. Welche M\u00f6glichkeiten Sie haben, das Kondensat abflie\u00dfen zu lassen, wie es entsteht und welche Folgen es nach sich ziehen kann, erfahren Sie im folgenden Artikel.<\/p>\n\n\n\n<h2>Inhalt<\/h2>\n\n\n\n<ul><li><a href=\"#Kondensat im Schornstein: Was ist das eigentlich?\">Kondensat im Schornstein: Was ist das eigentlich?<\/a><\/li><li><a href=\"#Wie entsteht Kondensat?\">Wie entsteht Kondensat?<\/a><\/li><li><a href=\"#M\u00f6gliche Folgen von Kondensat\">M\u00f6gliche Folgen von Kondensat<\/a><\/li><li><a href=\"#Kondensat auffangen\">Kondensat auffangen<\/a><\/li><li><a href=\"#Die richtige Entsorgung\">Die richtige Entsorgung<\/a><\/li><li><a href=\"#Neutralisationsanlagen\">Neutralisationsanlagen<\/a><\/li><li><a href=\"#FAQ\">FAQ<\/a><\/li><\/ul>\n\n\n\n<h2 id=\"Kondensat im Schornstein: Was ist das eigentlich?\">Kondensat im Schornstein: Was ist das eigentlich?<\/h2>\n\n\n\n<p>Einfach gesagt: Kondensat<strong> <\/strong>ist Fl\u00fcssigkeit, die sich<strong> innen am Schornstein sammelt<\/strong> und dann hinunterl\u00e4uft. Je nachdem, was der Rauch neben <strong>Wasserdampf<\/strong> noch enth\u00e4lt, m\u00fcssen Sie unterschiedliche Dinge beachten. Bis zu einer gewissen Menge ist Kondenswasser im Schornstein normal und wird bei modernen Gaskesseln sogar zur Energiegewinnung genutzt.<\/p>\n\n\n\n<pre class=\"wp-block-verse info gzw\"><strong>Gut zu wissen<\/strong>: Der Punkt, an dem Wasser im Schornstein kondensiert, hei\u00dft Taupunkt. Dieser liegt bei ungef\u00e4hr 50 Grad Celsius.<\/pre>\n\n\n\n<h3 id=\"Wie entsteht Kondensat?\">Wie entsteht Kondensat?<\/h3>\n\n\n\n<p>Kondensat entsteht, indem <strong>hei\u00dfe Abgase zu sehr abk\u00fchlen<\/strong>, w\u00e4hrend sie durch den Schlot abziehen. Das Rauchgas bildet kleine Wassertropfen an der Schornsteininnenseite und flie\u00dft nach unten. Das Kondensat kann verschiedene ph-Werte aufweisen, je nachdem, mit welchem Mittel Sie den Kamin befeuern. <strong>In geringen Mengen<\/strong> verursacht das Kondensat <strong>kaum Sch\u00e4den<\/strong> und ist sogar normal.<\/p>\n\n\n\n<div class=\"wp-container-1 wp-block-buttons\">\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link has-background\" href=\"https:\/\/www.feuer-fuchs.de\/blog\/kaminofen\/kaminrohr-reinigen-step-fur-step\" style=\"border-radius:9px;background-color:#5c0d36\"><strong>Erfahren Sie mehr zu <\/strong><strong>Kaminrohr reinigen&nbsp; \u2013 Step f\u00fcr Step<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>Ein anderer Grund f\u00fcr Kondensat oder einen feuchten Schornstein kann starker <strong>Regen<\/strong> sein. Dieser gelangt oft durch eine <strong>mangelnde oder mangelhafte Schornsteinkopfdichtung<\/strong> in die Innenseite. Oft kann bereits eine Schornsteinabdeckung Abhilfe verschaffen.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<pre class=\"wp-block-verse info gzw\"><strong>Gut zu wissen<\/strong>: M\u00f6gliche Gr\u00fcnde f\u00fcr Kondensat sind a)zu niedrige Verbrennungstemperaturen und b)starke Niederschl\u00e4ge, die in den Schornstein gelangen\n<\/pre>\n\n\n\n<p>Um zu niedrige Verbrennungstemperaturen zu vermeiden, ist es hilfreich zu wissen, wie Sie <a href=\"http:\/\/feuer-fuchs.de\/blog\/kaminofen\/mit-dem-kaminofen-richtig-heizen-darauf-sollten-sie-achten\">richtig mit Ihrem Kaminofen heizen<\/a>.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img src=\"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/11\/kaminofen-wassergefuehrt-la-nordica-loriet-s-dsa-168-kw-1024x1024.webp\" alt=\"Kaminofen wassergef\u00fchrt La Nordica Loriet S DSA - 16,8 kW von La Nordica S.P.A.\n\" class=\"wp-image-3353\" width=\"256\" height=\"256\" srcset=\"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/11\/kaminofen-wassergefuehrt-la-nordica-loriet-s-dsa-168-kw-1024x1024.webp 1024w, https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/11\/kaminofen-wassergefuehrt-la-nordica-loriet-s-dsa-168-kw-200x200.webp 200w, https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/11\/kaminofen-wassergefuehrt-la-nordica-loriet-s-dsa-168-kw-150x150.webp 150w, https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/11\/kaminofen-wassergefuehrt-la-nordica-loriet-s-dsa-168-kw-768x768.webp 768w, https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/11\/kaminofen-wassergefuehrt-la-nordica-loriet-s-dsa-168-kw.webp 1200w\" sizes=\"(max-width: 256px) 100vw, 256px\" \/><figcaption>Kaminofen wassergef\u00fchrt La Nordica Loriet S DSA &#8211; 16,8 kW von <a href=\"https:\/\/www.feuer-fuchs.de\/Marken\/La-Nordica-SpA\">La Nordica S.P.A.<\/a><br><\/figcaption><\/figure>\n\n\n\n<p><\/p>\n\n\n\n<h3 id=\"M\u00f6gliche Folgen von Kondensat\">M\u00f6gliche Folgen von Kondensat<\/h3>\n\n\n\n<p>Wenn sich jedoch zu viel Kondensat bildet, beginnt die Feuchtigkeit den Schornstein von innen heraus zu zersetzen. Ein gemauerter Schornstein wird so mit der Zeit <strong>por\u00f6s und instabil<\/strong>. Dieser Vorgang wird als <a href=\"https:\/\/www.feuer-fuchs.de\/blog\/kaminofen\/hilfe-mein-schornstein-ist-fleckig-versottung-folgen-und-loesungen\">Versottung<\/a> bezeichnet.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-container-2 wp-block-buttons\">\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link has-background\" href=\"https:\/\/www.feuer-fuchs.de\/blog\/kaminofen\/der-schornsteinfeger-so-oft-muss-er-zu-ihnen-kommen\" style=\"border-radius:9px;background-color:#5c0d36\"><strong>Lesen Sie jetzt: So oft muss der Schornsteinfeger zu Ihnen kommen<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>Aufwendige <strong>Reparaturen und Sanierungen<\/strong> sind oftmals die einzige M\u00f6glichkeit, fortgeschrittene Versottung zu beseitigen. Jedoch k\u00f6nnen Sie mit dem richtigen Auffangsystem Ihren Kamin vor diesen Folgen bewahren.&nbsp;<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-container-7 wp-block-group ffCTABanner\"><div class=\"wp-block-group__inner-container\">\n<div class=\"wp-container-6 wp-block-columns\">\n<div class=\"wp-container-3 wp-block-column\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image size-large\"><a class=\"ctaimg\" href=\"https:\/\/www.feuer-fuchs.de\" target=\"_blank\" rel=\"Feuer-Fuchs.de noopener\"><img width=\"493\" height=\"218\" src=\"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/03\/feuerfuchs_cta_banner_gfx.png\" alt=\"\" class=\"wp-image-2753\" srcset=\"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/03\/feuerfuchs_cta_banner_gfx.png 493w, https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/03\/feuerfuchs_cta_banner_gfx-340x150.png 340w\" sizes=\"(max-width: 493px) 100vw, 493px\" \/><\/a><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-container-5 wp-block-column\" style=\"flex-basis:33.33%\">\n<p>Jetzt das ganze Sortiment in unserem Webshop entdecken<\/p>\n\n\n\n<div class=\"wp-container-4 wp-block-buttons\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link no-border-radius\" href=\"https:\/\/www.feuer-fuchs.de\" target=\"_blank\" rel=\"noreferrer noopener\">zum Webshop<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<p><\/p>\n\n\n\n<h2 id=\"Kondensat auffangen\">Kondensat auffangen<\/h2>\n\n\n\n<p>Eine M\u00f6glichkeit, das entstandene Wasser aufzufangen, bilden <strong>Kondensatauffangbeutel<\/strong>. Diese werden am Fu\u00df des Kamins oder Schornsteins angebracht und m\u00fcssen <strong>regelm\u00e4\u00dfig per Hand geleert<\/strong> werden. Oft befinden sich diese Auffangbeh\u00e4lter hinter der Revisionsklappe.<\/p>\n\n\n\n<p>Entsorgen Sie das dort gesammelte Wasser ganz einfach <strong>in der Toilette oder dem Waschbecken<\/strong>.<\/p>\n\n\n\n<pre class=\"wp-block-verse info achtung\"><strong>Achtung<\/strong>: Wenn Sie den Auffangbeh\u00e4lter nicht regelm\u00e4\u00dfig leeren, riskieren Sie ungewollte Feuchtigkeit in den W\u00e4nden und m\u00fcssen mit kostspieligen Reparaturen und Sanierungen rechnen.<\/pre>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img src=\"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/11\/pelletofen-edilkamin-blade2-12-up-naturstein-121-kw-1-1024x1024.jpg\" alt=\"Pelletofen Edilkamin BLADE2 12 UP - 12,1 kW von Edelkamin\" class=\"wp-image-3355\" width=\"256\" height=\"256\" srcset=\"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/11\/pelletofen-edilkamin-blade2-12-up-naturstein-121-kw-1-1024x1024.jpg 1024w, https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/11\/pelletofen-edilkamin-blade2-12-up-naturstein-121-kw-1-200x200.jpg 200w, https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/11\/pelletofen-edilkamin-blade2-12-up-naturstein-121-kw-1-150x150.jpg 150w, https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/11\/pelletofen-edilkamin-blade2-12-up-naturstein-121-kw-1-768x768.jpg 768w, https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/11\/pelletofen-edilkamin-blade2-12-up-naturstein-121-kw-1.jpg 1200w\" sizes=\"(max-width: 256px) 100vw, 256px\" \/><figcaption>Pelletofen Edilkamin BLADE2 12 UP &#8211; 12,1 kW von <a href=\"https:\/\/www.feuer-fuchs.de\/Marken\/Edilkamin\">Edelkamin<\/a><\/figcaption><\/figure>\n\n\n\n<h2 id=\"Die richtige Entsorgung\">Die richtige Entsorgung<\/h2>\n\n\n\n<p>Meist ist ein <strong>Anschluss an die Hausentw\u00e4sserungsanlage<\/strong> die einfachste und sicherste Methode. Dabei sollten Sie jedoch die <strong>lokalen Bestimmungen Ihrer Abwasserbeh\u00f6rde<\/strong> einhalten. Dabei orientieren sich die meisten Vorgaben an generellen Vorschriften zur Abwasserentsorgung. Als Richtwert wird hier die 25-fache Menge an Abwasser im Verh\u00e4ltnis zum Kondensat genutzt. Falls Sie sich unsicher sind, wenden Sie sich an lokale Fachbetriebe und Abwasserbeh\u00f6rden.<\/p>\n\n\n\n<pre class=\"wp-block-verse info gzw\"><strong>Gut zu wissen<\/strong>: Am besten eignen sich s\u00e4ureresistente Rohre, wie PVC- oder Steinzeug-Rohre.\n<\/pre>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-container-8 wp-block-buttons\">\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link has-background\" href=\"https:\/\/www.feuer-fuchs.de\/blog\/kaminofen\/schornsteinmontage-wichtige-vorschriften\" style=\"border-radius:9px;background-color:#5c0d36\"><strong>Schornsteinmontage: Welche Vorschriften sind zu beachten? Lesen Sie jetzt!<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>Besonders einfach l\u00e4uft das Kondensat an Edelstahlschornsteinen hinunter. In der Regel sind diese mit einem Auffangbeh\u00e4lter ausgestattet und k\u00f6nnen an die Abwasserleitung des Hauses angeschlossen werden. Bei dieser L\u00f6sung empfiehlt es sich, ein <strong>Siphon mit Sperrfunktion<\/strong> einzusetzen, um eventuell zus\u00e4tzlich eine Neutralisationsanlage anzuschlie\u00dfen.<\/p>\n\n\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img src=\"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/11\/gussofen-jotul-f-377-v2-advance-high-top-schwarz-lackiert-bp-specksteinseiten-und-deckplatte-6-kw.jpg-1024x1024.webp\" alt=\"Kaminofen Jotul F 377 V2 Advance High Top - 6 kW von Jotul A\/S\" class=\"wp-image-3356\" width=\"256\" height=\"256\" srcset=\"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/11\/gussofen-jotul-f-377-v2-advance-high-top-schwarz-lackiert-bp-specksteinseiten-und-deckplatte-6-kw.jpg-1024x1024.webp 1024w, https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/11\/gussofen-jotul-f-377-v2-advance-high-top-schwarz-lackiert-bp-specksteinseiten-und-deckplatte-6-kw.jpg-200x200.webp 200w, https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/11\/gussofen-jotul-f-377-v2-advance-high-top-schwarz-lackiert-bp-specksteinseiten-und-deckplatte-6-kw.jpg-150x150.webp 150w, https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/11\/gussofen-jotul-f-377-v2-advance-high-top-schwarz-lackiert-bp-specksteinseiten-und-deckplatte-6-kw.jpg-768x768.webp 768w, https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/11\/gussofen-jotul-f-377-v2-advance-high-top-schwarz-lackiert-bp-specksteinseiten-und-deckplatte-6-kw.jpg.webp 1200w\" sizes=\"(max-width: 256px) 100vw, 256px\" \/><figcaption>Kaminofen Jotul F 377 V2 Advance High Top &#8211; 6 kW von <a href=\"https:\/\/www.feuer-fuchs.de\/Marken\/Jotul-A-S\">Jotul A\/S<\/a><\/figcaption><\/figure>\n\n\n\n<h3 id=\"Neutralisationsanlagen\">Neutralisationsanlagen<\/h3>\n\n\n\n<p>Die Installation einer Neutralisationsanlage bietet sich bei <strong>gr\u00f6\u00dferen Heizanlagen<\/strong> an. Bei solchen Anlagen verd\u00fcnnt sich das anfallende Kondensat meist nicht ausreichend mit dem Abwasser. Eine zwischengeschaltete Anlage neutralisiert das entstandene Kondenswasser und es flie\u00dft \u00fcber den Hausanschluss ab.<\/p>\n\n\n\n<p><\/p>\n\n\n\n<div class=\"wp-container-9 wp-block-buttons\">\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link has-background\" href=\"https:\/\/www.feuer-fuchs.de\/blog\/kaminofen\/kaminofen-leistung-in-kw\" style=\"border-radius:9px;background-color:#5c0d36\"><strong>Kaminofen-Leistung im Check \u2013 was bedeuten Kilowatt-Angaben? Jetzt lesen!<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<p>Als Orientierung dient ein ph-Wert von 4. Eine Neutralisierungsanlage reduziert den ph-Wert auf 6,5 \u2013 das verbleibende Wasser ist somit s\u00e4urearm genug. Die <strong>g\u00e4ngige Kombination<\/strong> in einer solchen Anlage besteht aus einem <strong>Filter<\/strong> (meist Aktivkohle) und einem <strong>Neutralisator<\/strong> (Granulat). Hier lassen Sie sich am besten fachlich bei dem Betrieb Ihres Vertrauens beraten.<\/p>\n\n\n\n<pre class=\"wp-block-verse info wichtig\"><strong>Fazit<\/strong>: Kein Ofen ist vor Feuchtigkeit im Schornsteininneren sicher. In kleinen Mengen und bei der richtigen Pflege Ihres Kamins tauchen selten Probleme auf. Bei kleinen Heizanlagen reicht ein Auffangbeh\u00e4lter f\u00fcr das Kondensat. \u00dcbersteigt Ihre Anlage jedoch 200 kW Heizleistung m\u00fcssen Sie sich um die Neutralisation des Kondenswassers k\u00fcmmern.<\/pre>\n\n\n\n<p><\/p>\n\n\n\n<h2>Passendes Zubeh\u00f6r bei Feuer-Fuchs finden!<\/h2>\n\n\n\n<p>Ob <a href=\"https:\/\/www.feuer-fuchs.de\/Kaminofen\">Kaminofen<\/a>, <a href=\"https:\/\/www.feuer-fuchs.de\/Pelletofen\">Pelletofen<\/a>, <a href=\"https:\/\/www.feuer-fuchs.de\/Holzherd-Kuechenherd\">K\u00fcchenherd<\/a> oder <a href=\"https:\/\/www.feuer-fuchs.de\/Wasserfuehrende-Kamine\">wassergef\u00fchrte Produkte<\/a>: Sie alle ben\u00f6tigen einen Schornstein, der gut gewartet ist.<\/p>\n\n\n\n<p>In unserem Shop finden Sie das passende <a href=\"https:\/\/www.feuer-fuchs.de\/Kaminzubehoer\">Kaminzubeh\u00f6r<\/a>, um Erosion oder Verschlei\u00df vorzubeugen. Jetzt entdecken und f\u00fcndig werden!<\/p>\n\n\n\n<div class=\"wp-container-10 wp-block-buttons\">\n<div class=\"wp-block-button aligncenter\"><a class=\"wp-block-button__link has-background\" href=\"https:\/\/www.feuer-fuchs.de\/Kaminzubehoer\" style=\"border-radius:9px;background-color:#5c0d36\"><strong>Zu dem Kaminzubeh\u00f6r in unserem Shop<\/strong><strong>.<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<p><\/p>\n\n\n\n<h2 id=\"FAQ\">FAQ<\/h2>\n\n\n        <section        class=\"sc_fs_faq sc_card\"\n\t\t        >\n\t\t\t\t<h2>Wie viel Kondenswasser ist normal im Schornstein\/ Kamin?<\/h2>\t\t        <div>\n\t\t\t                <figure class=\"sc_fs_faq__figure\">\n                    <a\n                            href=\"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/07\/morsoe-living-morsoe-forno-outdoor-ofen-150x150.jpg\"\n                            title=\"\"\n                     data-rel=\"lightbox-image-0\" data-rl_title=\"\" data-rl_caption=\"\">\n                        <img\n                                class=\"sc_fs_faq__image\"\n                                src=\"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/07\/morsoe-living-morsoe-forno-outdoor-ofen-150x150.jpg\"\n                                alt=\"\"\n                        >\n                    <\/a>\n                <\/figure>\n\t\t\t            <div class=\"sc_fs_faq__content\">\n\t\t\t\t\n\n<p>Eine genaue Mengenangabe ist schwer zu nennen, da es verschiedene Faktoren gibt, die hier Einfluss nehmen. Je nachdem, mit welchem Rohstoff sie heizen, k\u00f6nnen Sie sich an <strong>1,5 Liter Kondenswasser pro Kubikmeter Gas<\/strong> orientieren. Bei <strong>einem Liter Heiz\u00f6l<\/strong> sollten <strong>ca. 0,9 Liter Kondensat<\/strong> anfallen.<\/p>\n\n            <\/div>\n        <\/div>\n        <\/section>\n\t        <section        class=\"sc_fs_faq sc_card\"\n\t\t        >\n\t\t\t\t<h2>Wie entsorge ich Kondensat richtig?<\/h2>\t\t        <div>\n\t\t\t                <figure class=\"sc_fs_faq__figure\">\n                    <a\n                            href=\"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/12\/2025-04-03-gesammelte-Kondensat-in-Ihrer-Toilette-oder-Waschbecken-entsorgen-150x150.jpg\"\n                            title=\"\"\n                     data-rel=\"lightbox-image-1\" data-rl_title=\"\" data-rl_caption=\"\">\n                        <img\n                                class=\"sc_fs_faq__image\"\n                                src=\"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/12\/2025-04-03-gesammelte-Kondensat-in-Ihrer-Toilette-oder-Waschbecken-entsorgen-150x150.jpg\"\n                                alt=\"gesammelte Kondensat in Ihrer Toilette oder Waschbecken entsorgen\"\n                        >\n                    <\/a>\n                <\/figure>\n\t\t\t            <div class=\"sc_fs_faq__content\">\n\t\t\t\t\n\n<p>In der Regel k\u00f6nnen Sie das gesammelte Kondensat in Ihrer <strong>Toilette oder Waschbecken entsorgen<\/strong>.<\/p>\n\n            <\/div>\n        <\/div>\n        <\/section>\n\t        <section        class=\"sc_fs_faq sc_card\"\n\t\t        >\n\t\t\t\t<h2>Was tun bei Kondensat im Schornstein?<\/h2>\t\t        <div>\n\t\t\t                <figure class=\"sc_fs_faq__figure\">\n                    <a\n                            href=\"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/12\/Schornstein-Schmutzig-150x150.jpg\"\n                            title=\"\"\n                     data-rel=\"lightbox-image-2\" data-rl_title=\"\" data-rl_caption=\"\">\n                        <img\n                                class=\"sc_fs_faq__image\"\n                                src=\"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/12\/Schornstein-Schmutzig-150x150.jpg\"\n                                alt=\"Schornstein schmutzig\"\n                        >\n                    <\/a>\n                <\/figure>\n\t\t\t            <div class=\"sc_fs_faq__content\">\n\t\t\t\t\n\n<p>\u00dcberpr\u00fcfen Sie, ob Ihr Schornsteinkopf fachgerecht abgedichtet ist. Behalten Sie einen <strong>\u00dcberblick \u00fcber das Alter und das Aussehen Ihres Schornsteins<\/strong> (besonders bei gemauerten Varianten), um fr\u00fchzeitig Ver\u00e4nderungen zu erkennen.<\/p>\n\n            <\/div>\n        <\/div>\n        <\/section>\n\t        <section        class=\"sc_fs_faq sc_card\"\n\t\t        >\n\t\t\t\t<h2>Wie kann ich Kondensat vermeiden bzw. so gering wie m\u00f6glich halten?<\/h2>\t\t        <div>\n\t\t\t                <figure class=\"sc_fs_faq__figure\">\n                    <a\n                            href=\"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/10\/kaminofen-wassergefuehrt-justus-island-aqua-20-10-kw-150x150.png\"\n                            title=\"\"\n                     data-rel=\"lightbox-image-3\" data-rl_title=\"\" data-rl_caption=\"\">\n                        <img\n                                class=\"sc_fs_faq__image\"\n                                src=\"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/10\/kaminofen-wassergefuehrt-justus-island-aqua-20-10-kw-150x150.png\"\n                                alt=\"\"\n                        >\n                    <\/a>\n                <\/figure>\n\t\t\t            <div class=\"sc_fs_faq__content\">\n\t\t\t\t\n\n<p>Achten Sie auf einen <strong>angemessenen Durchschnitt ihres Kamins im Verh\u00e4ltnis zur Feuerstelle<\/strong>. Ihr Fachbetrieb des Vertrauens und auch der Schornsteinfeger stehten Ihnen hier zur Seite. Sorgen Sie zus\u00e4tzlich f\u00fcr eine <strong>passende Dichtung am Schornsteinkopf<\/strong>, um das Eindringen von Regenwasser so gering wie m\u00f6glich zu halten. Zus\u00e4tzlich k\u00f6nnen Sie den Zug in Ihrem Kamin bei Bedarf mit einer <a href=\"https:\/\/www.feuer-fuchs.de\/Externe-Verbrennungsluftzufuhr\">externen Luftzufuhr<\/a> erh\u00f6hen.<\/p>\n\n            <\/div>\n        <\/div>\n        <\/section>\n\t        <section        class=\"sc_fs_faq sc_card\"\n\t\t        >\n\t\t\t\t<h2>Welche Folgen kann Kondensat im Schornstein haben?\n<\/h2>\t\t        <div>\n\t\t\t                <figure class=\"sc_fs_faq__figure\">\n                    <a\n                            href=\"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2023\/05\/Schornstein-150x150.jpg\"\n                            title=\"\"\n                     data-rel=\"lightbox-image-4\" data-rl_title=\"\" data-rl_caption=\"\">\n                        <img\n                                class=\"sc_fs_faq__image\"\n                                src=\"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2023\/05\/Schornstein-150x150.jpg\"\n                                alt=\"\"\n                        >\n                    <\/a>\n                <\/figure>\n\t\t\t            <div class=\"sc_fs_faq__content\">\n\t\t\t\t\n\n<p>Das kondensierte Wasser kann den Schornstein von innen heraus zersetzen und zur sogenannten <strong>Versottung<\/strong> f\u00fchren. Eine vernachl\u00e4ssigte Ablaufanlage kann zus\u00e4tzlich zu unerw\u00fcnschter Feuchte in den W\u00e4nden f\u00fchren.<\/p>\n\n            <\/div>\n        <\/div>\n        <\/section>\n\t\n<script type=\"application\/ld+json\">\n    {\n        \"@context\": \"https:\/\/schema.org\",\n        \"@type\": \"FAQPage\",\n        \"mainEntity\": [\n                    {\n                \"@type\": \"Question\",\n                \"name\": \"Wie viel Kondenswasser ist normal im Schornstein\/ Kamin?\",\n                \"acceptedAnswer\": {\n                    \"@type\": \"Answer\",\n                    \"text\": \"\n\n<p>Eine genaue Mengenangabe ist schwer zu nennen, da es verschiedene Faktoren gibt, die hier Einfluss nehmen. Je nachdem, mit welchem Rohstoff sie heizen, k\u00f6nnen Sie sich an <strong>1,5 Liter Kondenswasser pro Kubikmeter Gas<\/strong> orientieren. Bei <strong>einem Liter Heiz\u00f6l<\/strong> sollten <strong>ca. 0,9 Liter Kondensat<\/strong> anfallen.<\/p>\n\n\"\n                                        ,\n                    \"image\" : {\n                        \"@type\" : \"ImageObject\",\n                        \"contentUrl\" : \"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/07\/morsoe-living-morsoe-forno-outdoor-ofen-150x150.jpg\"\n                    }\n                                    }\n            }\n            ,\t            {\n                \"@type\": \"Question\",\n                \"name\": \"Wie entsorge ich Kondensat richtig?\",\n                \"acceptedAnswer\": {\n                    \"@type\": \"Answer\",\n                    \"text\": \"\n\n<p>In der Regel k\u00f6nnen Sie das gesammelte Kondensat in Ihrer <strong>Toilette oder Waschbecken entsorgen<\/strong>.<\/p>\n\n\"\n                                        ,\n                    \"image\" : {\n                        \"@type\" : \"ImageObject\",\n                        \"contentUrl\" : \"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/12\/2025-04-03-gesammelte-Kondensat-in-Ihrer-Toilette-oder-Waschbecken-entsorgen-150x150.jpg\"\n                    }\n                                    }\n            }\n            ,\t            {\n                \"@type\": \"Question\",\n                \"name\": \"Was tun bei Kondensat im Schornstein?\",\n                \"acceptedAnswer\": {\n                    \"@type\": \"Answer\",\n                    \"text\": \"\n\n<p>\u00dcberpr\u00fcfen Sie, ob Ihr Schornsteinkopf fachgerecht abgedichtet ist. Behalten Sie einen <strong>\u00dcberblick \u00fcber das Alter und das Aussehen Ihres Schornsteins<\/strong> (besonders bei gemauerten Varianten), um fr\u00fchzeitig Ver\u00e4nderungen zu erkennen.<\/p>\n\n\"\n                                        ,\n                    \"image\" : {\n                        \"@type\" : \"ImageObject\",\n                        \"contentUrl\" : \"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/12\/Schornstein-Schmutzig-150x150.jpg\"\n                    }\n                                    }\n            }\n            ,\t            {\n                \"@type\": \"Question\",\n                \"name\": \"Wie kann ich Kondensat vermeiden bzw. so gering wie m\u00f6glich halten?\",\n                \"acceptedAnswer\": {\n                    \"@type\": \"Answer\",\n                    \"text\": \"\n\n<p>Achten Sie auf einen <strong>angemessenen Durchschnitt ihres Kamins im Verh\u00e4ltnis zur Feuerstelle<\/strong>. Ihr Fachbetrieb des Vertrauens und auch der Schornsteinfeger stehten Ihnen hier zur Seite. Sorgen Sie zus\u00e4tzlich f\u00fcr eine <strong>passende Dichtung am Schornsteinkopf<\/strong>, um das Eindringen von Regenwasser so gering wie m\u00f6glich zu halten. Zus\u00e4tzlich k\u00f6nnen Sie den Zug in Ihrem Kamin bei Bedarf mit einer <a>externen Luftzufuhr<\/a> erh\u00f6hen.<\/p>\n\n\"\n                                        ,\n                    \"image\" : {\n                        \"@type\" : \"ImageObject\",\n                        \"contentUrl\" : \"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/10\/kaminofen-wassergefuehrt-justus-island-aqua-20-10-kw-150x150.png\"\n                    }\n                                    }\n            }\n            ,\t            {\n                \"@type\": \"Question\",\n                \"name\": \"Welche Folgen kann Kondensat im Schornstein haben?\n\",\n                \"acceptedAnswer\": {\n                    \"@type\": \"Answer\",\n                    \"text\": \"\n\n<p>Das kondensierte Wasser kann den Schornstein von innen heraus zersetzen und zur sogenannten <strong>Versottung<\/strong> f\u00fchren. Eine vernachl\u00e4ssigte Ablaufanlage kann zus\u00e4tzlich zu unerw\u00fcnschter Feuchte in den W\u00e4nden f\u00fchren.<\/p>\n\n\"\n                                        ,\n                    \"image\" : {\n                        \"@type\" : \"ImageObject\",\n                        \"contentUrl\" : \"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2023\/05\/Schornstein-150x150.jpg\"\n                    }\n                                    }\n            }\n            \t        ]\n    }\n<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Ein guter Kondensatablauf f\u00fcr Ihren Schornstein verl\u00e4ngert das Leben Ihres Kamins und ist kein gro\u00dfer Aufwand, sowohl in der Montage<\/p>\n","protected":false},"author":2,"featured_media":4409,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"colormag_page_container_layout":"default_layout","colormag_page_sidebar_layout":"default_layout"},"categories":[2],"tags":[18],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Kondensat im Kamin: Das m\u00fcssen Sie wissen - Feuer-Fuchs<\/title>\n<meta name=\"description\" content=\"Alle wichtigen Informationen zu Kondenswasser im Schornstein \u27a4 Wie es entsteht und richtig entsorgt wird \u2714 Jetzt lesen!\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.feuer-fuchs.de\/blog\/kaminofen\/kondenswasser-im-schornstein-und-jetzt-das-koennen-sie-tun\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<meta name=\"twitter:title\" content=\"Kondensat im Kamin: Das m\u00fcssen Sie wissen - Feuer-Fuchs\" \/>\n<meta name=\"twitter:description\" content=\"Alle wichtigen Informationen zu Kondenswasser im Schornstein \u27a4 Wie es entsteht und richtig entsorgt wird \u2714 Jetzt lesen!\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/12\/Schornstein-mit-Kodenzwasser.jpg\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"Feuer Fuchs Redaktion\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kondensat im Kamin: Das m\u00fcssen Sie wissen - Feuer-Fuchs","description":"Alle wichtigen Informationen zu Kondenswasser im Schornstein \u27a4 Wie es entsteht und richtig entsorgt wird \u2714 Jetzt lesen!","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.feuer-fuchs.de\/blog\/kaminofen\/kondenswasser-im-schornstein-und-jetzt-das-koennen-sie-tun","twitter_card":"summary","twitter_title":"Kondensat im Kamin: Das m\u00fcssen Sie wissen - Feuer-Fuchs","twitter_description":"Alle wichtigen Informationen zu Kondenswasser im Schornstein \u27a4 Wie es entsteht und richtig entsorgt wird \u2714 Jetzt lesen!","twitter_image":"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/12\/Schornstein-mit-Kodenzwasser.jpg","twitter_misc":{"Verfasst von":"Feuer Fuchs Redaktion","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/www.feuer-fuchs.de\/blog\/#website","url":"https:\/\/www.feuer-fuchs.de\/blog\/","name":"Feuer-Fuchs KAMINMAGAZIN -","description":"Alles rund um den Kaminofen","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.feuer-fuchs.de\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.feuer-fuchs.de\/blog\/kaminofen\/kondenswasser-im-schornstein-und-jetzt-das-koennen-sie-tun#primaryimage","url":"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/12\/Schornstein-mit-Kodenzwasser.jpg","contentUrl":"https:\/\/www.feuer-fuchs.de\/blog\/wp-content\/uploads\/2022\/12\/Schornstein-mit-Kodenzwasser.jpg","width":1024,"height":512,"caption":"Schornstein mit Kondenswasser"},{"@type":"WebPage","@id":"https:\/\/www.feuer-fuchs.de\/blog\/kaminofen\/kondenswasser-im-schornstein-und-jetzt-das-koennen-sie-tun#webpage","url":"https:\/\/www.feuer-fuchs.de\/blog\/kaminofen\/kondenswasser-im-schornstein-und-jetzt-das-koennen-sie-tun","name":"Kondensat im Kamin: Das m\u00fcssen Sie wissen - Feuer-Fuchs","isPartOf":{"@id":"https:\/\/www.feuer-fuchs.de\/blog\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.feuer-fuchs.de\/blog\/kaminofen\/kondenswasser-im-schornstein-und-jetzt-das-koennen-sie-tun#primaryimage"},"datePublished":"2022-12-14T10:55:05+00:00","dateModified":"2025-04-03T12:33:07+00:00","author":{"@id":"https:\/\/www.feuer-fuchs.de\/blog\/#\/schema\/person\/eef09c3eee41dbc0dc0de26f10c46f90"},"description":"Alle wichtigen Informationen zu Kondenswasser im Schornstein \u27a4 Wie es entsteht und richtig entsorgt wird \u2714 Jetzt lesen!","breadcrumb":{"@id":"https:\/\/www.feuer-fuchs.de\/blog\/kaminofen\/kondenswasser-im-schornstein-und-jetzt-das-koennen-sie-tun#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.feuer-fuchs.de\/blog\/kaminofen\/kondenswasser-im-schornstein-und-jetzt-das-koennen-sie-tun"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.feuer-fuchs.de\/blog\/kaminofen\/kondenswasser-im-schornstein-und-jetzt-das-koennen-sie-tun#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.feuer-fuchs.de\/blog"},{"@type":"ListItem","position":2,"name":"Kondenswasser im Schornstein \u2013 und jetzt? Das k\u00f6nnen Sie tun!"}]},{"@type":"Person","@id":"https:\/\/www.feuer-fuchs.de\/blog\/#\/schema\/person\/eef09c3eee41dbc0dc0de26f10c46f90","name":"Feuer Fuchs Redaktion"}]}},"_links":{"self":[{"href":"https:\/\/www.feuer-fuchs.de\/blog\/wp-json\/wp\/v2\/posts\/3341"}],"collection":[{"href":"https:\/\/www.feuer-fuchs.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.feuer-fuchs.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.feuer-fuchs.de\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.feuer-fuchs.de\/blog\/wp-json\/wp\/v2\/comments?post=3341"}],"version-history":[{"count":25,"href":"https:\/\/www.feuer-fuchs.de\/blog\/wp-json\/wp\/v2\/posts\/3341\/revisions"}],"predecessor-version":[{"id":4671,"href":"https:\/\/www.feuer-fuchs.de\/blog\/wp-json\/wp\/v2\/posts\/3341\/revisions\/4671"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.feuer-fuchs.de\/blog\/wp-json\/wp\/v2\/media\/4409"}],"wp:attachment":[{"href":"https:\/\/www.feuer-fuchs.de\/blog\/wp-json\/wp\/v2\/media?parent=3341"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.feuer-fuchs.de\/blog\/wp-json\/wp\/v2\/categories?post=3341"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.feuer-fuchs.de\/blog\/wp-json\/wp\/v2\/tags?post=3341"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}